{"id":13459,"date":"2020-10-29T15:26:00","date_gmt":"2020-10-29T14:26:00","guid":{"rendered":"http:\/\/www.tepaseul-magazine.fr\/accueil\/?p=13459"},"modified":"2020-11-30T11:47:15","modified_gmt":"2020-11-30T10:47:15","slug":"pressotherapie","status":"publish","type":"post","link":"https:\/\/www.tepaseul-magazine.fr\/accueil\/pressotherapie\/","title":{"rendered":"PRESSOTHERAPIE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">BIEN DANS SES BOTTES AVEC COMPEX AYRE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une nouveaut\u00e9 en r\u00e9cup\u00e9ration compressive sans fil !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">COMPEX AYRE contribue \u00e0 am\u00e9liorer la circulation sanguine et lymphatique pour soulager les jambes lourdes, drainer les toxines pour mieux r\u00e9cup\u00e9rer apr\u00e8s un effort sportif intense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pratique pour b\u00e9n\u00e9ficier d\u2019un soulagement n\u2019importe o\u00f9, \u00e0 n\u2019importe quel moment ! Les bottes COMPEX AYRE sont con\u00e7ues pour tous aussi bien sportifs que non sportifs, les entraineurs et les pr\u00e9parateurs physiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">COMPEX AYRE utilise une compression dynamique puls\u00e9e dans les membres inf\u00e9rieurs, sous forme de vagues pendant son temps d\u2019utilisation, ce qui aide \u00e0 procurer un soulagement rapide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LES BIENFAITS DE COMPEX AYRE<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Utile pour traiter et pr\u00e9venir les muscles endoloris \/ gonfl\u00e9s<\/li><li>Id\u00e9al pour aider \u00e0 soulager les muscles fatigu\u00e9s apr\u00e8s l\u2019exercice ou le sport et permettre d\u2019\u00eatre de nouveau \u00e0 fond d\u00e8sle lendemain.<\/li><li>Favorise le retour veineux et lymphatique<\/li><li>Favorise l\u2019\u00e9limination des toxines<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">SP\u00c9CIFICIT\u00c9S<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Transportable partout, aucun c\u00e2ble<br>\u2022 4 chambres de compression ind\u00e9pendantes pouvant \u00eatre gonfl\u00e9es s\u00e9par\u00e9ment ou simultan\u00e9ment \u2022 2 modes : gonflage des 4 chambres les unes apr\u00e8s les autres ou les 4 simultan\u00e9ment<br>\u2022 Batterie rechargeable permettant jusqu\u2019\u00e0 3h d\u2019utilisation \u00e0 la puissance maximale<br>\u2022 Rev\u00eatement int\u00e9rieur et ext\u00e9rieur de haute qualit\u00e9, hypo allerg\u00e9nique pour un nettoyage ais\u00e9<br>\u2022 T\u00e9l\u00e9commande int\u00e9gr\u00e9e sur la botte<br>\u2022 Compression puissante ajustable de 10 en 10 de 0 \u00e0 120 mmHg<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prix de vente public conseill\u00e9 : 599,99 \u20acTTC&nbsp;\/ Disponible en ligne sur :&nbsp;https:\/\/www.compex.com\/fr\/compex-fixx-1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00c0 propos de Compex<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Marque sp\u00e9cialis\u00e9e, depuis plus de 30 ans, dans les domaines de la r\u00e9\u00e9ducation, du traitement de la douleur et de l\u2019entrainement sportif gr\u00e2ce \u00e0 l\u2019\u00e9lectrostimulation, Compex est une marque d\u2019origine suisse appartenant au groupe international DJO qui compte 280 salari\u00e9s en France. Bas\u00e9e pr\u00e8s de Bayonne, Compex est leader sur le march\u00e9 de l\u2019\u00e9lectrostimulation et se distingue sur le march\u00e9 par ses stimulateurs qui sont tous des appareils m\u00e9dicaux de classe IIA, soutenus par des \u00e9tudes cliniques prouvant leur efficacit\u00e9. &#8211;&nbsp;<\/em><em>www.compex.com\/fr<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BIEN DANS SES BOTTES AVEC COMPEX AYRE Une nouveaut\u00e9 en r\u00e9cup\u00e9ration compressive sans fil ! COMPEX AYRE contribue \u00e0 am\u00e9liorer la circulation sanguine et lymphatique pour soulager les jambes lourdes, drainer les toxines pour mieux r\u00e9cup\u00e9rer apr\u00e8s un effort sportif intense. Pratique pour b\u00e9n\u00e9ficier d\u2019un&#8230;<\/p>\n","protected":false},"author":2,"featured_media":13278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,54],"tags":[],"class_list":["post-13459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medecines-et-medecines-douces","category-sante"],"_links":{"self":[{"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/posts\/13459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/comments?post=13459"}],"version-history":[{"count":1,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/posts\/13459\/revisions"}],"predecessor-version":[{"id":13461,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/posts\/13459\/revisions\/13461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/media\/13278"}],"wp:attachment":[{"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/media?parent=13459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/categories?post=13459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tepaseul-magazine.fr\/accueil\/wp-json\/wp\/v2\/tags?post=13459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}